{"id":1578,"date":"2017-04-12T14:54:17","date_gmt":"2017-04-12T13:54:17","guid":{"rendered":"https:\/\/linhardttest.pixeltypen.de\/?p=1578"},"modified":"2017-04-12T14:54:47","modified_gmt":"2017-04-12T13:54:47","slug":"zertifizierte-innovationsmanager-ihk","status":"publish","type":"post","link":"https:\/\/linhardttest.pixeltypen.de\/index.php\/zertifizierte-innovationsmanager-ihk\/","title":{"rendered":"Zertifizierte Innovationsmanager IHK"},"content":{"rendered":"<p><a href=\"https:\/\/linhardttest.pixeltypen.de\/wp-content\/uploads\/2017\/04\/innomanager2.jpg\"><em><strong><img title=\"innomanager\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-1579\" src=\"https:\/\/linhardttest.pixeltypen.de\/wp-content\/uploads\/2017\/04\/innomanager2-150x150.jpg\" alt=\"\" \/><\/strong><\/em><\/a><strong>Viechtach <\/strong>&#8211; Grundlagen des Innovationsmanagements, Kreativmethoden und erfinderisches Probleml\u00c3\u00b6sen standen beim Workshop f\u00c3\u00bcr die angehenden Innovationsmanager auf dem Lehrplan. Im Fokus stand aber nicht nur die Kreativit\u00c3\u00a4t, sondern auch deren praktische Anwendung im beruflichen Alltag. <!--more-->So waren auch Verkn\u00c3\u00bcpfungen zum Projektmanagement, Prozessorientierung, Ver\u00c3\u00a4nderungsmanagement und der betriebswirtschaftliche Blick auf Innovationen Teil der 12 Tage dauernden Ausbildung. Angeboten wurde die Seminarreihe von Cluster Sensorik e. V. in Partnerschaft mit der IHK Passau, durchgef\u00c3\u00bchrt wurde sie vom Produzenten f\u00c3\u00bcr flexible Kunststoffverpackungen Bischof + Klein aus Konzell. Die Referenten kamen von Hochschule und Wirtschaft, sodass ein guter Mix aus Theorie und praktischer Anwendung angeboten werden konnte.<\/p>\n<p>F\u00c3\u00bcnf F\u00c3\u00bchrungskr\u00c3\u00a4fte absolvierten am Ende der Seminarreihe eine zweist\u00c3\u00bcndige Pr\u00c3\u00bcfung, die sie mit Bravour abschlossen. Stefan Feldmeier, Sabine Schmidt, Christian Jungwirth, Torsten Sch\u00c3\u00a4fer und Stefan Ernst d\u00c3\u00bcrfen sich nun offiziell &#8220;IHK Innovationsmanager&#8221; nennen. Die frisch gebackenen Absolventen werden bei LINHARDT nun ihre erlernten F\u00c3\u00a4higkeiten dazu nutzen, den bereits begonnenen Wandel hin zur Innovationskultur zu unterst\u00c3\u00bctzen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viechtach &#8211; Grundlagen des Innovationsmanagements, Kreativmethoden und erfinderisches Probleml\u00c3\u00b6sen standen beim Workshop f\u00c3\u00bcr die angehenden Innovationsmanager auf dem Lehrplan. Im Fokus stand aber nicht nur die Kreativit\u00c3\u00a4t, sondern auch deren praktische Anwendung im beruflichen Alltag.<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/posts\/1578"}],"collection":[{"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/comments?post=1578"}],"version-history":[{"count":0,"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/posts\/1578\/revisions"}],"wp:attachment":[{"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/media?parent=1578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/categories?post=1578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linhardttest.pixeltypen.de\/index.php\/wp-json\/wp\/v2\/tags?post=1578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}